{"id":18615,"date":"2022-07-12T17:52:36","date_gmt":"2022-07-12T20:52:36","guid":{"rendered":"https:\/\/senadorwellingtonfagundes.com.br\/senador\/?p=18615"},"modified":"2022-07-12T17:59:35","modified_gmt":"2022-07-12T20:59:35","slug":"nota-de-pesar","status":"publish","type":"post","link":"https:\/\/senadorwellingtonfagundes.com.br\/senador\/nota-de-pesar\/","title":{"rendered":"Nota de Pesar"},"content":{"rendered":"\n<p>\u00c9 com imensa tristeza que comunicamos o falecimento da nossa querida jornalista ISA RAMOS, companheira do dia-a-dia por muitos anos. Isa lutou bravamente contra um c\u00e2ncer de pulm\u00e3o, mas por miseric\u00f3rdia divina foi levada aos bra\u00e7os do Pai. N\u00f3s, fam\u00edlia e equipe WF, pedimos a todos que se mantenham em ora\u00e7\u00e3o pela alma da nossa colega e por todos os seus familiares, para que os anjos da guarda a recebam com o mesmo amor com o qual ela viveu e tratou a todos, igualmente.<\/p>\n\n\n\n<p>Iremos nos lembrar com carinho de cada momento que dividimos com ela e de cada demonstra\u00e7\u00e3o do amor pela vida. Esperamos, por fim, que nossas ora\u00e7\u00f5es a alcancem como um verdadeiro &#8220;at\u00e9 logo&#8221;.<\/p>\n\n\n\n<p>Isa Ramos deixa 03 filhos (Kayo, Ge\u00f3rgia, Mauro) e 06 netos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9 com imensa tristeza que comunicamos o falecimento da nossa querida jornalista ISA RAMOS, companheira do dia-a-dia por muitos anos. Isa lutou bravamente contra um c\u00e2ncer de pulm\u00e3o, mas por miseric\u00f3rdia divina foi levada aos&#8230;<\/p>\n","protected":false},"author":21,"featured_media":18619,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[319],"tags":[],"_links":{"self":[{"href":"https:\/\/senadorwellingtonfagundes.com.br\/senador\/wp-json\/wp\/v2\/posts\/18615"}],"collection":[{"href":"https:\/\/senadorwellingtonfagundes.com.br\/senador\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senadorwellingtonfagundes.com.br\/senador\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senadorwellingtonfagundes.com.br\/senador\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/senadorwellingtonfagundes.com.br\/senador\/wp-json\/wp\/v2\/comments?post=18615"}],"version-history":[{"count":1,"href":"https:\/\/senadorwellingtonfagundes.com.br\/senador\/wp-json\/wp\/v2\/posts\/18615\/revisions"}],"predecessor-version":[{"id":18617,"href":"https:\/\/senadorwellingtonfagundes.com.br\/senador\/wp-json\/wp\/v2\/posts\/18615\/revisions\/18617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senadorwellingtonfagundes.com.br\/senador\/wp-json\/wp\/v2\/media\/18619"}],"wp:attachment":[{"href":"https:\/\/senadorwellingtonfagundes.com.br\/senador\/wp-json\/wp\/v2\/media?parent=18615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senadorwellingtonfagundes.com.br\/senador\/wp-json\/wp\/v2\/categories?post=18615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senadorwellingtonfagundes.com.br\/senador\/wp-json\/wp\/v2\/tags?post=18615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}